{"id":3,"count":60,"description":"\u30d6\u30ed\u30b0\u904b\u55b6\u306b\u95a2\u3059\u308b\u8a18\u4e8b\u4e00\u89a7\u30da\u30fc\u30b8\u3067\u3059\u3002","link":"https:\/\/lolipop.jp\/media\/category\/start-blog\/","name":"\u30d6\u30ed\u30b0\u904b\u55b6","slug":"start-blog","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/lolipop.jp\/media\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lolipop.jp\/media\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lolipop.jp\/media\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lolipop.jp\/media\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}